{"id":126,"date":"2016-04-19T20:03:23","date_gmt":"2016-04-19T20:03:23","guid":{"rendered":"http:\/\/hikingbolivia.com\/?p=126"},"modified":"2016-04-19T20:03:23","modified_gmt":"2016-04-19T20:03:23","slug":"climbing-pequeno-alpamayo-5-370-m-17-613-ft-escalada-3-dias","status":"publish","type":"post","link":"http:\/\/hikingbolivia.com\/en\/climbing-pequeno-alpamayo-5-370-m-17-613-ft-escalada-3-dias\/","title":{"rendered":"PEQUE\u00d1O ALPAMAYO 5.370m 3 days."},"content":{"rendered":"<style id=\"bwg-style-0\">    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails {      width: 904px;              justify-content: center;        margin:0 auto !important;              background-color: rgba(255, 255, 255, 0.00);            padding-left: 4px;      padding-top: 4px;      max-width: 100%;            }        #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item {    justify-content: flex-start;      max-width: 180px;            width: 180px !important;          }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item a {       margin-right: 4px;       margin-bottom: 4px;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item0 {      padding: 0px;            background-color:rgba(255,255,255, 0.30);      border: 0px none #CCCCCC;      opacity: 1.00;      border-radius: 0;      box-shadow: 0px 0px 0px #888888;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img {      max-height: none;      max-width: none;      padding: 0 !important;    }        @media only screen and (min-width: 480px) {      #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item0 {        transition: all 0.3s ease 0s;-webkit-transition: all 0.3s ease 0s;      }      #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item0:hover {        -ms-transform: scale(1.1);        -webkit-transform: scale(1.1);        transform: scale(1.1);      }    }          #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 {      padding-top: 50%;    }        #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-title2,    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-ecommerce2 {      color: #CCCCCC;      font-family: segoe ui;      font-size: 16px;      font-weight: bold;      padding: 2px;      text-shadow: 0px 0px 0px #888888;      max-height: 100%;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-thumb-description span {    color: #323A45;    font-family: Ubuntu;    font-size: 12px;    max-height: 100%;    word-wrap: break-word;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-play-icon2 {      font-size: 32px;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-ecommerce2 {      font-size: 19.2px;      color: #CCCCCC;    }    <\/style>    <div id=\"bwg_container1_0\"         class=\"bwg_container bwg_thumbnail bwg_thumbnails \"         data-right-click-protection=\"0\"         data-bwg=\"0\"         data-scroll=\"0\"         data-gallery-type=\"thumbnails\"         data-gallery-view-type=\"thumbnails\"         data-current-url=\"http:\/\/hikingbolivia.com\/en\/wp-json\/wp\/v2\/posts\/126\"         data-lightbox-url=\"http:\/\/hikingbolivia.com\/wp-admin\/admin-ajax.php?action=GalleryBox&#038;current_view=0&#038;gallery_id=16&#038;tag=0&#038;theme_id=1&#038;shortcode_id=16&#038;sort_by=order&#038;order_by=asc&#038;current_url=http%3A%2F%2Fhikingbolivia.com%2Fen%2Fwp-json%2Fwp%2Fv2%2Fposts%2F126\"         data-gallery-id=\"16\"         data-popup-width=\"800\"         data-popup-height=\"500\"         data-is-album=\"gallery\"         data-buttons-position=\"bottom\">      <div id=\"bwg_container2_0\">             <div id=\"ajax_loading_0\" class=\"bwg_loading_div_1\">      <div class=\"bwg_loading_div_2\">        <div class=\"bwg_loading_div_3\">          <div id=\"loading_div_0\" class=\"bwg_spider_ajax_loading\">          <\/div>        <\/div>      <\/div>    <\/div>            <form id=\"gal_front_form_0\"              class=\"bwg-hidden\"              method=\"post\"              action=\"#\"              data-current=\"0\"              data-shortcode-id=\"16\"              data-gallery-type=\"thumbnails\"              data-gallery-id=\"16\"              data-tag=\"0\"              data-album-id=\"0\"              data-theme-id=\"1\"              data-ajax-url=\"http:\/\/hikingbolivia.com\/wp-admin\/admin-ajax.php?action=bwg_frontend_data\">          <div id=\"bwg_container3_0\" class=\"bwg-background bwg-background-0\">                <div data-max-count=\"5\"         data-thumbnail-width=\"180\"         data-bwg=\"0\"         data-gallery-id=\"16\"         data-lightbox-url=\"http:\/\/hikingbolivia.com\/wp-admin\/admin-ajax.php?action=GalleryBox&amp;current_view=0&amp;gallery_id=16&amp;tag=0&amp;theme_id=1&amp;shortcode_id=16&amp;sort_by=order&amp;order_by=asc&amp;current_url=http%3A%2F%2Fhikingbolivia.com%2Fen%2Fwp-json%2Fwp%2Fv2%2Fposts%2F126\"         id=\"bwg_thumbnails_0\"         class=\"bwg-container-0 bwg-thumbnails bwg-standard-thumbnails bwg-container bwg-border-box\">            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"177\" href=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/P1010211.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"177\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/thumb\/P1010211.jpg\"                   src=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/thumb\/P1010211.jpg\"                   alt=\"P1010211\"                   title=\"P1010211\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                <div class=\"bwg-title1\"><div class=\"bwg-title2\">P1010211<\/div><\/div>        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"176\" href=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/DSC_2913.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"176\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/thumb\/DSC_2913.jpg\"                   src=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/thumb\/DSC_2913.jpg\"                   alt=\"DSC 2913\"                   title=\"DSC 2913\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                <div class=\"bwg-title1\"><div class=\"bwg-title2\">DSC 2913<\/div><\/div>        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"175\" href=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/DSC_2898.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"175\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/thumb\/DSC_2898.jpg\"                   src=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/thumb\/DSC_2898.jpg\"                   alt=\"DSC 2898\"                   title=\"DSC 2898\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                <div class=\"bwg-title1\"><div class=\"bwg-title2\">DSC 2898<\/div><\/div>        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"174\" href=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/DSC_0579.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"174\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/thumb\/DSC_0579.jpg\"                   src=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/thumb\/DSC_0579.jpg\"                   alt=\"DSC 0579\"                   title=\"DSC 0579\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                <div class=\"bwg-title1\"><div class=\"bwg-title2\">DSC 0579<\/div><\/div>        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"173\" href=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/DSC_0481.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"173\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/thumb\/DSC_0481.jpg\"                   src=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/thumb\/DSC_0481.jpg\"                   alt=\"DSC 0481\"                   title=\"DSC 0481\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                <div class=\"bwg-title1\"><div class=\"bwg-title2\">DSC 0481<\/div><\/div>        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"172\" href=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/DSC04132.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"172\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/thumb\/DSC04132.jpg\"                   src=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/thumb\/DSC04132.jpg\"                   alt=\"DSC04132\"                   title=\"DSC04132\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                <div class=\"bwg-title1\"><div class=\"bwg-title2\">DSC04132<\/div><\/div>        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"171\" href=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/DSC04114.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"171\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/thumb\/DSC04114.jpg\"                   src=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/thumb\/DSC04114.jpg\"                   alt=\"DSC04114\"                   title=\"DSC04114\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                <div class=\"bwg-title1\"><div class=\"bwg-title2\">DSC04114<\/div><\/div>        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"170\" href=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/DSC04102.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"170\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/thumb\/DSC04102.jpg\"                   src=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/thumb\/DSC04102.jpg\"                   alt=\"DSC04102\"                   title=\"DSC04102\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                <div class=\"bwg-title1\"><div class=\"bwg-title2\">DSC04102<\/div><\/div>        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"169\" href=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/DSC04097.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"169\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/thumb\/DSC04097.jpg\"                   src=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/thumb\/DSC04097.jpg\"                   alt=\"DSC04097\"                   title=\"DSC04097\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                <div class=\"bwg-title1\"><div class=\"bwg-title2\">DSC04097<\/div><\/div>        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"168\" href=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/DSC03424.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"168\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/thumb\/DSC03424.jpg\"                   src=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/thumb\/DSC03424.jpg\"                   alt=\"DSC03424\"                   title=\"DSC03424\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                <div class=\"bwg-title1\"><div class=\"bwg-title2\">DSC03424<\/div><\/div>        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"167\" href=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/Amigos-de-Mexico-y-Canada-405.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"167\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/thumb\/Amigos-de-Mexico-y-Canada-405.jpg\"                   src=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/thumb\/Amigos-de-Mexico-y-Canada-405.jpg\"                   alt=\"Amigos-de-Mexico-y-Canada-405\"                   title=\"Amigos-de-Mexico-y-Canada-405\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                <div class=\"bwg-title1\"><div class=\"bwg-title2\">Amigos-de-Mexico-y-Canada-405<\/div><\/div>        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"166\" href=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/19.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"166\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/thumb\/19.jpg\"                   src=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/thumb\/19.jpg\"                   alt=\"19\"                   title=\"19\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                <div class=\"bwg-title1\"><div class=\"bwg-title2\">19<\/div><\/div>        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"165\" href=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/10.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"165\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/thumb\/10.jpg\"                   src=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/thumb\/10.jpg\"                   alt=\"10\"                   title=\"10\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                <div class=\"bwg-title1\"><div class=\"bwg-title2\">10<\/div><\/div>        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"164\" href=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/08-(2).jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"164\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/thumb\/08-(2).jpg\"                   src=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/photo-gallery\/pequeno%20alpamayo\/thumb\/08-(2).jpg\"                   alt=\"08-(2)\"                   title=\"08-(2)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                <div class=\"bwg-title1\"><div class=\"bwg-title2\">08-(2)<\/div><\/div>        <\/a>              <\/div>          <\/div>    <style>      \/*pagination styles*\/      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 {\t\t\t\ttext-align: center;\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: segoe ui;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tmargin: 6px 0 4px;\t\t\t\tdisplay: block;      }      @media only screen and (max-width : 320px) {      #bwg_container1_0 #bwg_container2_0 .displaying-num_0 {     \t display: none;      }      }      #bwg_container1_0 #bwg_container2_0 .displaying-num_0 {\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: segoe ui;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tmargin-right: 10px;\t\t\t\tvertical-align: middle;      }      #bwg_container1_0 #bwg_container2_0 .paging-input_0 {\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: segoe ui;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tvertical-align: middle;      }      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled:hover,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled:focus,\t\t\t#bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 input.bwg_current_page {\t\t\t\tcursor: default;\t\t\t\tcolor: rgba(102, 102, 102, 0.5);      }      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 input.bwg_current_page {\t\t\t\tcursor: pointer;\t\t\t\ttext-align: center;\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: segoe ui;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\ttext-decoration: none;\t\t\t\tpadding: 3px 6px;\t\t\t\tmargin: 0;\t\t\t\tborder-radius: 0;\t\t\t\tborder-style: solid;\t\t\t\tborder-width: 1px;\t\t\t\tborder-color: #E3E3E3;\t\t\t\t\t\t\t\tbackground-color: rgba(255, 255, 255, 1.00);\t\t\t\tbox-shadow: 0;\t\t\t\ttransition: all 0.3s ease 0s;-webkit-transition: all 0.3s ease 0s;      }      <\/style>      <span class=\"bwg_nav_cont_0\">              <div class=\"tablenav-pages_0\">                  <\/div>                <input type=\"hidden\" id=\"page_number_0\" name=\"page_number_0\" value=\"1\" \/>      <script type=\"text\/javascript\">        if( jQuery('.bwg_nav_cont_0').length > 1 ) {          jQuery('.bwg_nav_cont_0').first().remove()        }        function spider_page_0(cur, x, y, load_more) {          if (typeof load_more == \"undefined\") {            var load_more = false;          }          if (jQuery(cur).hasClass('disabled')) {            return false;          }          var items_county_0 = 1;          switch (y) {            case 1:              if (x >= items_county_0) {                document.getElementById('page_number_0').value = items_county_0;              }              else {                document.getElementById('page_number_0').value = x + 1;              }              break;            case 2:              document.getElementById('page_number_0').value = items_county_0;              break;            case -1:              if (x == 1) {                document.getElementById('page_number_0').value = 1;              }              else {                document.getElementById('page_number_0').value = x - 1;              }              break;            case -2:              document.getElementById('page_number_0').value = 1;              break;\t\t\t\t\t\tcase 0:              document.getElementById('page_number_0').value = x;              break;            default:              document.getElementById('page_number_0').value = 1;          }          bwg_ajax('gal_front_form_0', '0', 'bwg_thumbnails_0', '0', '', 'gallery', 0, '', '', load_more, '', 1);        }                    jQuery('.first-page-0').on('click', function () {              spider_page_0(this, 1, -2, 'numeric');              return false;            });            jQuery('.prev-page-0').on('click', function () {              spider_page_0(this, 1, -1, 'numeric');              return false;            });            jQuery('.next-page-0').on('click', function () {              spider_page_0(this, 1, 1, 'numeric');              return false;            });            jQuery('.last-page-0').on('click', function () {              spider_page_0(this, 1, 2, 'numeric');              return false;            });        \t\t\t\t\/* Change page on input enter. *\/        function bwg_change_page_0( e, that ) {          if (  e.key == 'Enter' ) {            var to_page = parseInt(jQuery(that).val());            var pages_count = jQuery(that).parents(\".pagination-links\").data(\"pages-count\");            var current_url_param = jQuery(that).attr('data-url-info');            if (to_page > pages_count) {              to_page = 1;            }\t \t\t\t\t\t\t\t\t\t\t\t\tspider_page_0(this, to_page, 0, 'numeric');\t\t\t\t\t\t\treturn false;\t\t\t\t\t\t          }          return true;        }        jQuery('.bwg_load_btn_0').on('click', function () {            spider_page_0(this, 1, 1, true);            return false;        });      <\/script>      <\/span>                <\/div>        <\/form>        <style>          #bwg_container1_0 #bwg_container2_0 #spider_popup_overlay_0 {          background-color: #000000;          opacity: 0.70;          }          <\/style>        <div id=\"bwg_spider_popup_loading_0\" class=\"bwg_spider_popup_loading\"><\/div>        <div id=\"spider_popup_overlay_0\" class=\"spider_popup_overlay\" onclick=\"spider_destroypopup(1000)\"><\/div>        <input type=\"hidden\" id=\"bwg_random_seed_0\" value=\"178062294\">                <\/div>    <\/div>    <script>      if (document.readyState === 'complete') {        if( typeof bwg_main_ready == 'function' ) {          if ( jQuery(\"#bwg_container1_0\").height() ) {            bwg_main_ready(jQuery(\"#bwg_container1_0\"));          }        }      } else {        document.addEventListener('DOMContentLoaded', function() {          if( typeof bwg_main_ready == 'function' ) {            if ( jQuery(\"#bwg_container1_0\").height() ) {             bwg_main_ready(jQuery(\"#bwg_container1_0\"));            }          }        });      }    <\/script>    \n<p>Day 1.- LA PAZ &#8211; TUNI &#8211; BASE CAMP\u00a0CONDORIRI<\/p>\n<p>We left La Paz and 09:00 am after two and a half hour journey we arrived at the Laguna Tuni, where we leave the vehicle. After some preparations with mules,\u00a0we start\u00a0a three-hour trek to the base camp Condoriri &#8211; Lagunja Ch\u00b4iyara Quta 4,700 m. Where we do camping place and rest\u00a0the\u00a0night after the dinner.<\/p>\n<p>Day 2.- HIKING PICO AUSTRIA 5.300M.<\/p>\n<p>After breakfast we hiki to Pico Ausria 5.300m in tre hours and half passsing nice landscape of the area, with forest and animal of the place, from the top enjoy the group of the mountain of the Condoriri area, Titicaca lake and all Altiplano area, after that return in two hours and half to the same camping place and rest.<\/p>\n<p>Day 3.-\u00a0BASE CAMP &#8211; SUMMIT &#8211; LA PAZ<\/p>\n<p>At 00:00 am prepare the climbing equipment after breakfast,\u00a0we start the climbing the Peque\u00f1o Alpamayo\u00a05.370m after 5 &#8211; 6 hour arrive to the summit, and then continue to descent to the base camp rest a half hour, continue to walking to Tuni in two hours,\u00a0where the transport waith for the group and return to La Paz in the afternoon.<\/p>\n<p>INCLUDED:<\/p>\n<p>* Private transportation.<br \/>\n* Mountain Guide.<br \/>\n* Cook.<br \/>\n* Mules and muler man.<br \/>\n* Food 2 lunch, 1 dinner and 1 breakfast.<br \/>\n* Camping equipment tent and sleeping mat.<br \/>\n* Mountain equipment.<br \/>\n* Dining tent.<br \/>\n*Cook equipment.<\/p>\n<p>NOT INCLUDED:<\/p>\n<p>* Sleeping bag.<br \/>\n* Sun glasses.<br \/>\n* Head lamp.<br \/>\n* Sun cream.<br \/>\n* Warm clothes.<br \/>\n* National Park entrance.<br \/>\n* Backpack 60 liters.<br \/>\n* Backpack 5 liters.<br \/>\n* Snack chocolates and water.<br \/>\n* Personal Insurance.<\/p>\n<div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f49-o1\" lang=\"es-ES\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/posts\/126#wpcf7-f49-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"49\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.6.2\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f49-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<h2>Booking \/ Reservas<\/h2>\n<p>Nombre (requerido)<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/p>\n<p>Correo electr\u00f3nico (requerido)<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/p>\n<p>Asunto<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input type=\"text\" name=\"your-subject\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" \/><\/span> <\/p>\n<p>Mensaje<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\"><\/textarea><\/span> <\/p>\n<p><label> Type here this text <input type=\"hidden\" name=\"_wpcf7_captcha_challenge_captcha-codez\" value=\"1854832368\" \/><img class=\"wpcf7-form-control wpcf7-captchac wpcf7-captcha-captcha-codez\" width=\"72\" height=\"24\" alt=\"captcha\" src=\"http:\/\/hikingbolivia.com\/wp-content\/uploads\/wpcf7_captcha\/1854832368.png\" \/><br \/> Here: <span class=\"wpcf7-form-control-wrap\" data-name=\"captcha-codez\"><input type=\"text\" name=\"captcha-codez\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-captchar\" autocomplete=\"off\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><input type=\"submit\" value=\"Enviar\" class=\"wpcf7-form-control has-spinner wpcf7-submit\" \/><\/p>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Day 1.- LA PAZ &#8211; TUNI &#8211; BASE CAMP\u00a0CONDORIRI We left La Paz and 09:00 am after two and a half hour journey we arrived at the Laguna Tuni, where we leave the vehicle. After some preparations with mules,\u00a0we start\u00a0a three-hour trek to the base camp Condoriri &#8211; Lagunja Ch\u00b4iyara Quta 4,700 m. Where we&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[2],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PEQUE\u00d1O ALPAMAYO 5.370m 3 days. - Hiking Bolivia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hikingbolivia.com\/en\/climbing-pequeno-alpamayo-5-370-m-17-613-ft-escalada-3-dias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PEQUE\u00d1O ALPAMAYO 5.370m 3 days. - Hiking Bolivia\" \/>\n<meta property=\"og:description\" content=\"Day 1.- LA PAZ &#8211; TUNI &#8211; BASE CAMP\u00a0CONDORIRI We left La Paz and 09:00 am after two and a half hour journey we arrived at the Laguna Tuni, where we leave the vehicle. After some preparations with mules,\u00a0we start\u00a0a three-hour trek to the base camp Condoriri &#8211; Lagunja Ch\u00b4iyara Quta 4,700 m. Where we...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hikingbolivia.com\/en\/climbing-pequeno-alpamayo-5-370-m-17-613-ft-escalada-3-dias\/\" \/>\n<meta property=\"og:site_name\" content=\"Hiking Bolivia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hikingboliviatours\/?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-19T20:03:23+00:00\" \/>\n<meta name=\"author\" content=\"adminHik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"adminHik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/hikingbolivia.com\/en\/climbing-pequeno-alpamayo-5-370-m-17-613-ft-escalada-3-dias\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/hikingbolivia.com\/en\/climbing-pequeno-alpamayo-5-370-m-17-613-ft-escalada-3-dias\/\"},\"author\":{\"name\":\"adminHik\",\"@id\":\"https:\/\/hikingbolivia.com\/en\/#\/schema\/person\/f492a19209ceb2ab97ce3fa41d5218f9\"},\"headline\":\"PEQUE\u00d1O ALPAMAYO 5.370m 3 days.\",\"datePublished\":\"2016-04-19T20:03:23+00:00\",\"dateModified\":\"2016-04-19T20:03:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/hikingbolivia.com\/en\/climbing-pequeno-alpamayo-5-370-m-17-613-ft-escalada-3-dias\/\"},\"wordCount\":274,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/hikingbolivia.com\/en\/#organization\"},\"articleSection\":[\"Climbing\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/hikingbolivia.com\/en\/climbing-pequeno-alpamayo-5-370-m-17-613-ft-escalada-3-dias\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hikingbolivia.com\/en\/climbing-pequeno-alpamayo-5-370-m-17-613-ft-escalada-3-dias\/\",\"url\":\"https:\/\/hikingbolivia.com\/en\/climbing-pequeno-alpamayo-5-370-m-17-613-ft-escalada-3-dias\/\",\"name\":\"PEQUE\u00d1O ALPAMAYO 5.370m 3 days. - Hiking Bolivia\",\"isPartOf\":{\"@id\":\"https:\/\/hikingbolivia.com\/en\/#website\"},\"datePublished\":\"2016-04-19T20:03:23+00:00\",\"dateModified\":\"2016-04-19T20:03:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/hikingbolivia.com\/en\/climbing-pequeno-alpamayo-5-370-m-17-613-ft-escalada-3-dias\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hikingbolivia.com\/en\/climbing-pequeno-alpamayo-5-370-m-17-613-ft-escalada-3-dias\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hikingbolivia.com\/en\/climbing-pequeno-alpamayo-5-370-m-17-613-ft-escalada-3-dias\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/hikingbolivia.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PEQUE\u00d1O ALPAMAYO 5.370m 3 days.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hikingbolivia.com\/en\/#website\",\"url\":\"https:\/\/hikingbolivia.com\/en\/\",\"name\":\"Hiking Bolivia\",\"description\":\"Alberth Bolivia Tours\",\"publisher\":{\"@id\":\"https:\/\/hikingbolivia.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hikingbolivia.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hikingbolivia.com\/en\/#organization\",\"name\":\"Hiking Bolivia Tours1\",\"url\":\"https:\/\/hikingbolivia.com\/en\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/hikingboliviatours\/?fref=ts\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/hikingbolivia.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hikingbolivia.com\/wp-content\/uploads\/2020\/05\/logo-hiking.png\",\"contentUrl\":\"https:\/\/hikingbolivia.com\/wp-content\/uploads\/2020\/05\/logo-hiking.png\",\"width\":250,\"height\":236,\"caption\":\"Hiking Bolivia Tours1\"},\"image\":{\"@id\":\"https:\/\/hikingbolivia.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/hikingbolivia.com\/en\/#\/schema\/person\/f492a19209ceb2ab97ce3fa41d5218f9\",\"name\":\"adminHik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/hikingbolivia.com\/en\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/0.gravatar.com\/avatar\/f330d33aa9c4136bd334b1f27a6f453f?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/0.gravatar.com\/avatar\/f330d33aa9c4136bd334b1f27a6f453f?s=96&d=mm&r=g\",\"caption\":\"adminHik\"},\"url\":\"http:\/\/hikingbolivia.com\/en\/author\/adminhik\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PEQUE\u00d1O ALPAMAYO 5.370m 3 days. - Hiking Bolivia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hikingbolivia.com\/en\/climbing-pequeno-alpamayo-5-370-m-17-613-ft-escalada-3-dias\/","og_locale":"en_US","og_type":"article","og_title":"PEQUE\u00d1O ALPAMAYO 5.370m 3 days. - Hiking Bolivia","og_description":"Day 1.- LA PAZ &#8211; TUNI &#8211; BASE CAMP\u00a0CONDORIRI We left La Paz and 09:00 am after two and a half hour journey we arrived at the Laguna Tuni, where we leave the vehicle. After some preparations with mules,\u00a0we start\u00a0a three-hour trek to the base camp Condoriri &#8211; Lagunja Ch\u00b4iyara Quta 4,700 m. Where we...","og_url":"https:\/\/hikingbolivia.com\/en\/climbing-pequeno-alpamayo-5-370-m-17-613-ft-escalada-3-dias\/","og_site_name":"Hiking Bolivia","article_publisher":"https:\/\/www.facebook.com\/hikingboliviatours\/?fref=ts","article_published_time":"2016-04-19T20:03:23+00:00","author":"adminHik","twitter_card":"summary_large_image","twitter_misc":{"Written by":"adminHik","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hikingbolivia.com\/en\/climbing-pequeno-alpamayo-5-370-m-17-613-ft-escalada-3-dias\/#article","isPartOf":{"@id":"https:\/\/hikingbolivia.com\/en\/climbing-pequeno-alpamayo-5-370-m-17-613-ft-escalada-3-dias\/"},"author":{"name":"adminHik","@id":"https:\/\/hikingbolivia.com\/en\/#\/schema\/person\/f492a19209ceb2ab97ce3fa41d5218f9"},"headline":"PEQUE\u00d1O ALPAMAYO 5.370m 3 days.","datePublished":"2016-04-19T20:03:23+00:00","dateModified":"2016-04-19T20:03:23+00:00","mainEntityOfPage":{"@id":"https:\/\/hikingbolivia.com\/en\/climbing-pequeno-alpamayo-5-370-m-17-613-ft-escalada-3-dias\/"},"wordCount":274,"commentCount":0,"publisher":{"@id":"https:\/\/hikingbolivia.com\/en\/#organization"},"articleSection":["Climbing"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hikingbolivia.com\/en\/climbing-pequeno-alpamayo-5-370-m-17-613-ft-escalada-3-dias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hikingbolivia.com\/en\/climbing-pequeno-alpamayo-5-370-m-17-613-ft-escalada-3-dias\/","url":"https:\/\/hikingbolivia.com\/en\/climbing-pequeno-alpamayo-5-370-m-17-613-ft-escalada-3-dias\/","name":"PEQUE\u00d1O ALPAMAYO 5.370m 3 days. - Hiking Bolivia","isPartOf":{"@id":"https:\/\/hikingbolivia.com\/en\/#website"},"datePublished":"2016-04-19T20:03:23+00:00","dateModified":"2016-04-19T20:03:23+00:00","breadcrumb":{"@id":"https:\/\/hikingbolivia.com\/en\/climbing-pequeno-alpamayo-5-370-m-17-613-ft-escalada-3-dias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hikingbolivia.com\/en\/climbing-pequeno-alpamayo-5-370-m-17-613-ft-escalada-3-dias\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hikingbolivia.com\/en\/climbing-pequeno-alpamayo-5-370-m-17-613-ft-escalada-3-dias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/hikingbolivia.com\/en\/"},{"@type":"ListItem","position":2,"name":"PEQUE\u00d1O ALPAMAYO 5.370m 3 days."}]},{"@type":"WebSite","@id":"https:\/\/hikingbolivia.com\/en\/#website","url":"https:\/\/hikingbolivia.com\/en\/","name":"Hiking Bolivia","description":"Alberth Bolivia Tours","publisher":{"@id":"https:\/\/hikingbolivia.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hikingbolivia.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/hikingbolivia.com\/en\/#organization","name":"Hiking Bolivia Tours1","url":"https:\/\/hikingbolivia.com\/en\/","sameAs":["https:\/\/www.facebook.com\/hikingboliviatours\/?fref=ts"],"logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hikingbolivia.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/hikingbolivia.com\/wp-content\/uploads\/2020\/05\/logo-hiking.png","contentUrl":"https:\/\/hikingbolivia.com\/wp-content\/uploads\/2020\/05\/logo-hiking.png","width":250,"height":236,"caption":"Hiking Bolivia Tours1"},"image":{"@id":"https:\/\/hikingbolivia.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/hikingbolivia.com\/en\/#\/schema\/person\/f492a19209ceb2ab97ce3fa41d5218f9","name":"adminHik","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hikingbolivia.com\/en\/#\/schema\/person\/image\/","url":"http:\/\/0.gravatar.com\/avatar\/f330d33aa9c4136bd334b1f27a6f453f?s=96&d=mm&r=g","contentUrl":"http:\/\/0.gravatar.com\/avatar\/f330d33aa9c4136bd334b1f27a6f453f?s=96&d=mm&r=g","caption":"adminHik"},"url":"http:\/\/hikingbolivia.com\/en\/author\/adminhik\/"}]}},"_links":{"self":[{"href":"http:\/\/hikingbolivia.com\/en\/wp-json\/wp\/v2\/posts\/126"}],"collection":[{"href":"http:\/\/hikingbolivia.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hikingbolivia.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hikingbolivia.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hikingbolivia.com\/en\/wp-json\/wp\/v2\/comments?post=126"}],"version-history":[{"count":1,"href":"http:\/\/hikingbolivia.com\/en\/wp-json\/wp\/v2\/posts\/126\/revisions"}],"predecessor-version":[{"id":127,"href":"http:\/\/hikingbolivia.com\/en\/wp-json\/wp\/v2\/posts\/126\/revisions\/127"}],"wp:attachment":[{"href":"http:\/\/hikingbolivia.com\/en\/wp-json\/wp\/v2\/media?parent=126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hikingbolivia.com\/en\/wp-json\/wp\/v2\/categories?post=126"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hikingbolivia.com\/en\/wp-json\/wp\/v2\/tags?post=126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}